{"id":59871,"date":"2026-07-15T13:16:55","date_gmt":"2026-07-15T13:16:55","guid":{"rendered":"https:\/\/www.globalrescue.com\/puede-la-experiencia-vencer-la-fiebre-de-las-cumbres-ed-viesturs-reflexiona-sobre-una-vida-por-encima-de-las-nubes\/"},"modified":"2026-07-15T13:16:55","modified_gmt":"2026-07-15T13:16:55","slug":"puede-la-experiencia-vencer-la-fiebre-de-las-cumbres-ed-viesturs-reflexiona-sobre-una-vida-por-encima-de-las-nubes","status":"publish","type":"post","link":"https:\/\/www.globalrescue.com\/es\/common\/blog\/detail\/puede-la-experiencia-vencer-la-fiebre-de-las-cumbres-ed-viesturs-reflexiona-sobre-una-vida-por-encima-de-las-nubes\/","title":{"rendered":"\u00bfPuede la experiencia vencer la \u00abfiebre de las cumbres\u00bb? Ed Viesturs reflexiona sobre una vida por encima de las nubes"},"content":{"rendered":"<h2>Art\u00edculo destacado:<\/h2>\n<ul>\n<li>Ed Viesturs explica por qu\u00e9 el buen juicio, y no la fuerza, es la habilidad de supervivencia m\u00e1s importante en las monta\u00f1as m\u00e1s altas del mundo.<\/li>\n<li>Las expediciones comerciales han facilitado el acceso a las grandes cumbres, pero han reducido las oportunidades que tienen los escaladores de desarrollar habilidades esenciales para la monta\u00f1a.<\/li>\n<li>El cambio clim\u00e1tico est\u00e1 modificando r\u00e1pidamente las rutas cl\u00e1sicas de escalada, acortando las temporadas y aumentando los riesgos objetivos.<\/li>\n<li>El hacinamiento, la \u00abfiebre de la cima\u00bb y la toma de decisiones err\u00f3neas siguen siendo algunos de los mayores peligros por encima de los 8.000 metros.<\/li>\n<li>El respeto hacia los gu\u00edas ind\u00edgenas, el trabajo en equipo y la humildad son fundamentales para el futuro del alpinismo responsable.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<style>\n\t.newsletter-wrapper {\n\t\tpadding: 30px;\n\t\tborder-radius: 10px;\n\t\tbackground-color: #F5F7FE;\n\t}\n\t.newsletter-wrapper h3 {\n\t\tfont-size: 24px;\n\t\tline-height: 28px;\n\t}\n\t.newsletter-wrapper button[type=\"submit\"] {\n\t\tfont-size: 12px;\n\t}\n\n\t.newsletter-wrapper .gr-asterisk.form-control-feedback {\n\t\ttop: -10px;\n\t}\n\t@media (min-width: 768px) {\n\t\t.width-35 {\n\t\t\twidth: 34%;\n\t\t}\n\n\t\t.width-25 {\n\t\t\twidth: 28%;\n\t\t}\n\t}\n<\/style>\n<form id=\"newsletter-form\" role=\"form\" class=\"newsletter-form gr-form\" novalidate>\n\t<div class=\"newsletter-wrapper\">\n\t\t<h3 class=\"fw-bold mb-3\">Informaci\u00f3n exclusiva sobre viajes, Mensual<\/h3>\n\t\t<p class=\"mb-4\">Reciba nuestro bolet\u00edn mensual para obtener informaci\u00f3n privilegiada sobre viajes, inspiraci\u00f3n sobre destinos y noticias \u00fatiles.<\/p>\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-5 has-feedback width-35\">\n\t\t\t\t<input type=\"text\" name=\"firstName\" maxlength=\"100\"\n\t\t\t\t\tclass=\"form-control gr-form-control newsletter-firstname mb-2\" placeholder=\"Nombre\"\n\t\t\t\t\tdata-gr-required data-gr-name \/>\n\t\t\t\t<span class=\"gr gr-asterisk color-danger small-icon form-control-feedback\" aria-hidden=\"true\"><\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-md-5 has-feedback width-35\">\n\t\t\t\t<input type=\"email\" name=\"email\" maxlength=\"100\"\n\t\t\t\t\tclass=\"form-control gr-form-control newsletter-email mb-2\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\"\n\t\t\t\t\tdata-gr-required data-gr-email \/>\n\t\t\t\t<span class=\"gr gr-asterisk color-danger small-icon form-control-feedback\" aria-hidden=\"true\"><\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-md-2 width-25\">\n\t\t\t\t<button type=\"submit\" id=\"submit-grcom-newsletter-signup\"\n\t\t\t\t\tclass=\"btn btn-danger btn-block btn-subscribe newsletter-blog-submit\" data-event data-eventcategory=\"Button\">\n\t\t\t\t\tSUSCRIBETE\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div id=\"gr-newsletter-captcha\" class=\"gr-captcha text-center mt-2\"><\/div>\n\t\t<div id=\"result\" class=\"message help-block bg-success alert-dismissable gr-alert-success\"><\/div>\n\t\t<div id=\"resultFailure\" class=\"message help-block alert-dismissable gr-alert-danger\"><\/div>\n\t<\/div>\n<\/form>\n<p>&nbsp;<\/p>\n<p>Pocos nombres inspiran mayor respeto en el mundo del alpinismo que el de Ed Viesturs. Considerado por muchos como uno de los mejores escaladores de alta monta\u00f1a de su generaci\u00f3n, Viesturs se convirti\u00f3 en el primer estadounidense en coronar las catorce cumbres de 8.000 metros del mundo sin ox\u00edgeno suplementario. Su carrera abarca d\u00e9cadas de expediciones por el Himalaya, el Karak\u00f3rum y otras cordilleras legendarias, lo que le ha valido una reputaci\u00f3n por su disciplina a la hora de tomar decisiones, su excepcional criterio y su compromiso inquebrantable de regresar a casa sano y salvo.  <\/p>\n<p>En la actualidad, Viesturs forma parte del Consejo Asesor de Monta\u00f1a de Global Rescue, un grupo de \u00e9lite compuesto por escaladores y profesionales de la monta\u00f1a reconocidos internacionalmente que asesoran a Global Rescue sobre las nuevas tendencias, la seguridad en las expediciones, las operaciones de rescate y los retos espec\u00edficos a los que se enfrentan los alpinistas de todo el mundo. Su experiencia contribuye a garantizar que las capacidades m\u00e9dicas y de rescate de Global Rescue sigan satisfaciendo las exigencias en constante evoluci\u00f3n del alpinismo moderno, ya sea prestando apoyo a escaladores en el Everest, a excursionistas en Nepal o a equipos de expedici\u00f3n que operan en algunos de los entornos m\u00e1s remotos del mundo. <\/p>\n<p>Global Rescue se reuni\u00f3 recientemente con Viesturs para hablar sobre la evoluci\u00f3n del alpinismo, el liderazgo bajo presi\u00f3n y lo que los escaladores de hoy en d\u00eda deben tener en cuenta antes de adentrarse en las altas monta\u00f1as.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.globalrescue.com\/grcom\/Ed-Viesturs-head-shot-802x1024.jpg\" alt=\"Un primer plano de Ed Viesturs\" width=\"640\" height=\"817\" class=\"aligncenter size-large wp-image-59868\" srcset=\"https:\/\/www.globalrescue.com\/grcom\/Ed-Viesturs-head-shot-802x1024.jpg 802w, https:\/\/www.globalrescue.com\/grcom\/Ed-Viesturs-head-shot-235x300.jpg 235w, https:\/\/www.globalrescue.com\/grcom\/Ed-Viesturs-head-shot-768x980.jpg 768w, https:\/\/www.globalrescue.com\/grcom\/Ed-Viesturs-head-shot.jpg 900w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2><\/h2>\n<h2>El legendario alpinista Ed Viesturs reflexiona sobre una vida pasada en las cimas m\u00e1s altas del mundo<\/h2>\n<p><em><strong>GLOBAL RESCUE: Cuando se superan los l\u00edmites absolutos de la capacidad humana, \u00bfc\u00f3mo se distingue entre la capacidad f\u00edsica m\u00e1xima y el punto de no retorno?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Esa es una de las preguntas m\u00e1s dif\u00edciles de responder, porque no hay un indicador sencillo que te diga cu\u00e1ndo has sobrepasado el l\u00edmite. A medida que asciendes y pasas largos periodos a altitudes extremas, la fatiga se va acumulando poco a poco. Especialmente el d\u00eda de la ascensi\u00f3n a la cima, est\u00e1s evaluando constantemente tu fuerza, tu resistencia y tu lucidez mental.  <\/p>\n<p>La experiencia se convierte en tu mayor baza. Si escalas por tu cuenta, dependes de todo lo que has aprendido a lo largo de los a\u00f1os en la monta\u00f1a. Si vas acompa\u00f1ado de compa\u00f1eros o gu\u00edas, es posible que ellos detecten se\u00f1ales sutiles de agotamiento antes que t\u00fa.  <\/p>\n<p>Con demasiada frecuencia, los escaladores se exceden m\u00e1s all\u00e1 de sus l\u00edmites de resistencia simplemente porque est\u00e1n decididos a alcanzar la cima. Lo dan todo para llegar arriba y luego se derrumban durante el descenso. En mi opini\u00f3n, ese es uno de los principales factores que contribuyen a los accidentes graves y a las muertes en el alpinismo de alta monta\u00f1a.  <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: \u00bfC\u00f3mo valoras el cambio de la escalada alpina tradicional y autosuficiente a las expediciones modernas y altamente comercializadas?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Las expediciones comerciales han hecho que las monta\u00f1as m\u00e1s altas del mundo sean accesibles para mucha m\u00e1s gente, pero han cambiado radicalmente la experiencia de la escalada.<\/p>\n<p>Hoy en d\u00eda, las empresas de organizaci\u00f3n de expediciones despliegan equipos enormes semanas antes de la llegada de los clientes. Se transportan las cargas, se montan los campamentos, se fijan las cuerdas desde el campamento base hasta la cima y gran parte de la infraestructura ya est\u00e1 preparada antes de que los escaladores comiencen su ascenso. <\/p>\n<p>Los clientes suelen dedicar su tiempo a aclimatarse, pero es posible que nunca participen en el transporte de cargas, el montaje de campamentos, el fijado de cuerdas o la preparaci\u00f3n de comidas. En muchos casos, simplemente se enganchan a las cuerdas fijas y escalan. <\/p>\n<p>La consecuencia desafortunada es que muchos alpinistas nunca llegan a aprender del todo lo que se necesita para organizar y llevar a cabo con seguridad una gran expedici\u00f3n al Himalaya. Esas experiencias desarrollan el criterio, la confianza y la autonom\u00eda, cualidades que resultan inestimables cuando las condiciones, inevitablemente, se deterioran. <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: \u00bfC\u00f3mo han influido el cambio clim\u00e1tico y el r\u00e1pido deshielo de las rutas hist\u00f3ricas en vuestro enfoque a la hora de planificar las expediciones y garantizar la seguridad?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> El cambio clim\u00e1tico est\u00e1 transformando las monta\u00f1as de formas que ya podemos observar cada temporada.<\/p>\n<p>Las temperaturas m\u00e1s c\u00e1lidas llegan antes, lo que significa que la nieve y el hielo empiezan a derretirse antes. Las rutas que antes eran relativamente estables quedan ahora al descubierto mucho antes, lo que aumenta el riesgo de desprendimientos de rocas, ca\u00eddas de hielo y otros peligros objetivos. <\/p>\n<p>Creo que las expediciones tendr\u00e1n que ir adaptando cada vez m\u00e1s sus calendarios. En lugar de comenzar una expedici\u00f3n al Everest en abril y terminarla a principios de junio, es posible que los equipos tengan que empezar en marzo y esperar terminarla a finales de abril, antes de que las condiciones empeoren. <\/p>\n<p>Las monta\u00f1as cambian constantemente. Los escaladores que tienen \u00e9xito se adaptan, en lugar de dar por sentado que la ruta del a\u00f1o pasado seguir\u00e1 siendo segura este a\u00f1o. <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: \u00bfQu\u00e9 medidas concretas debe adoptar la comunidad internacional de escaladores para resolver el problema del exceso de gente y los atascos en las \u00abzonas de la muerte\u00bb a gran altitud?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Gran parte de esa responsabilidad recae en los organizadores de expediciones.<\/p>\n<p>Cuando por fin llega el buen tiempo, casi todo el mundo quiere aprovechar lo que creen que puede ser la \u00fanica oportunidad para alcanzar la cima. Ah\u00ed es donde la \u00abfiebre de la cima\u00bb y el \u00abpensamiento de grupo\u00bb se vuelven peligrosos. <\/p>\n<p>Ning\u00fan gu\u00eda quiere decirles a sus clientes que se quedan esperando mientras todos los dem\u00e1s suben. Eso genera una presi\u00f3n enorme para seguir al resto del grupo. <\/p>\n<p>Algunos de los gu\u00edas m\u00e1s experimentados tienen la suficiente confianza como para hacer exactamente lo contrario. Dejan pasar el ajetreo inicial, observan c\u00f3mo evolucionan las condiciones y realizan su intento de ascensi\u00f3n a la cima m\u00e1s tarde. A menudo se encuentran con muchos menos escaladores y disfrutan de una experiencia m\u00e1s segura porque han actuado con paciencia en lugar de con prisas.  <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: \u00bfPodr\u00edas explicarnos c\u00f3mo piensas en un momento de peligro inminente y c\u00f3mo logras apartar el miedo para tomar decisiones que salvan vidas?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Lo primero es no entrar en p\u00e1nico.<\/p>\n<p>El p\u00e1nico lleva a tomar decisiones irracionales, y las decisiones irracionales suelen empeorar una situaci\u00f3n ya de por s\u00ed mala.<\/p>\n<p>En cambio, eval\u00faas con calma todo lo que tienes a tu disposici\u00f3n. \u00bfQu\u00e9 nivel tiene el equipo? \u00bfQu\u00e9 material queda? \u00bfCu\u00e1nta luz diurna te queda? \u00bfCu\u00e1les son las condiciones meteorol\u00f3gicas? \u00bfQu\u00e9 opciones te quedan?     <\/p>\n<p>O bien se toma una decisi\u00f3n colectiva, o bien se deja la decisi\u00f3n en manos del miembro del equipo con m\u00e1s experiencia. Las buenas decisiones tomadas de forma meditada son casi siempre mejores que las decisiones precipitadas impulsadas por la emoci\u00f3n. <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: A la luz de las recientes reflexiones sobre la seguridad a gran altitud y el acoso, \u00bfqu\u00e9 debe cambiar para garantizar un entorno m\u00e1s seguro y equitativo para las mujeres en las expediciones?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Es un asunto lamentable que merece una atenci\u00f3n seria.<\/p>\n<p>Las mujeres deben sentirse seguras en todas las expediciones guiadas y en cualquier entorno de monta\u00f1a profesional. Se debe fomentar la presentaci\u00f3n de quejas, investigarlas a fondo y tomarlas en serio. <\/p>\n<p>Si se confirman las acusaciones, los responsables no deber\u00edan seguir ejerciendo su labor de gu\u00eda.<\/p>\n<p>Con demasiada frecuencia, estas situaciones se minimizan o se ignoran. Eso tiene que cambiar si queremos que la gente conf\u00ede en la comunidad de escaladores. <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: M\u00e1s all\u00e1 de los precios de seis cifras de las expediciones comerciales modernas, \u00bfcu\u00e1l crees que es el coste humano o \u00e9tico no cuantificado de la industria del alpinismo actual?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Durante d\u00e9cadas, los porteadores de las tierras bajas y los sherpas de alta monta\u00f1a han constituido la columna vertebral de las expediciones exitosas al Himalaya.<\/p>\n<p>A veces se les considera simplemente como mano de obra, en lugar de como personas.<\/p>\n<p>No son trabajadores an\u00f3nimos. Son personas con nombre, familia y responsabilidades. En situaciones de emergencia, merecen el mismo respeto y consideraci\u00f3n que cualquier otra persona que se encuentre en la monta\u00f1a.  <\/p>\n<p>El sector de la escalada depende de ellos, y esa contribuci\u00f3n nunca deber\u00eda pasarse por alto.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: \u00bfC\u00f3mo deber\u00eda evolucionar la relaci\u00f3n entre los escaladores internacionales y los gu\u00edas ind\u00edgenas para garantizar una remuneraci\u00f3n justa, la seguridad y el reconocimiento?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Afortunadamente, creo que vamos por buen camino.<\/p>\n<p>Los gu\u00edas de Nepal, Pakist\u00e1n y otros lugares han desarrollado habilidades t\u00e9cnicas y de liderazgo a la altura de cualquier otro en el mundo. Cada vez m\u00e1s, se est\u00e1n convirtiendo en aut\u00e9nticos socios en la toma de decisiones, en lugar de limitarse a prestar apoyo a las expediciones occidentales. <\/p>\n<p>El alpinismo comercial genera unos ingresos enormes. Los gu\u00edas ind\u00edgenas, los trabajadores de alta monta\u00f1a y los porteadores merecen una remuneraci\u00f3n justa, respeto profesional y oportunidades de promoci\u00f3n en todo el sector. <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: Dada la creciente popularidad de la escalada en roc\u00f3dromo, \u00bfqu\u00e9 aspectos fundamentales de la \u00e9tica de la escalada al aire libre y qu\u00e9 habilidades de supervivencia se est\u00e1n pasando por alto en la formaci\u00f3n de esta nueva generaci\u00f3n de escaladores?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> La escalada en roc\u00f3dromo es un punto de partida fant\u00e1stico.<\/p>\n<p>Permite a las personas desarrollar la movilidad, la fuerza y las habilidades t\u00e9cnicas en un entorno controlado.<\/p>\n<p>La lecci\u00f3n m\u00e1s importante se aprende cuando los escaladores pasan a practicar al aire libre. La naturaleza no cuenta con suelos acolchados, temperaturas controladas ni condiciones predecibles. <\/p>\n<p>Es de esperar que los escaladores noveles sean conscientes de que las consecuencias son mucho m\u00e1s graves cuando se adentran en un entorno monta\u00f1oso sin control. El respeto por las condiciones meteorol\u00f3gicas, los riesgos objetivos, la orientaci\u00f3n y la toma de decisiones deben ser tan importantes como la propia habilidad para escalar. <\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>GLOBAL RESCUE: Al echar la vista atr\u00e1s a tu legendaria carrera, \u00bfqu\u00e9 te gustar\u00eda que fuera tu legado perdurable: las cimas que has conquistado o los caminos que has allanado para los dem\u00e1s?<\/strong><\/em><\/p>\n<p><strong>VIESTURS:<\/strong> Nunca escal\u00e9 para dejar un legado.<\/p>\n<p>Quer\u00eda sentirme bien por lo que hab\u00eda conseguido y, lo que es igual de importante, por c\u00f3mo lo hab\u00eda conseguido.<\/p>\n<p>Las monta\u00f1as me ense\u00f1aron lecciones que iban mucho m\u00e1s all\u00e1 de la escalada: el trabajo en equipo, la paciencia, la humildad, la gesti\u00f3n de riesgos y la toma de decisiones meditada.<\/p>\n<p>Si hay algo que perdure, espero que sea el hecho de haber dado ejemplo discretamente y haber demostrado que el \u00e9xito no se mide solo por llegar a la cima. Se mide por tomar buenas decisiones y volver a casa sano y salvo. <\/p>\n<p>&nbsp;<\/p>\n<h2>La conexi\u00f3n Global Rescue<\/h2>\n<p>Durante m\u00e1s de dos d\u00e9cadas, Global Rescue ha ayudado a alpinistas, excursionistas y viajeros de aventura a explorar con seguridad los entornos m\u00e1s exigentes del mundo. Desde su fundaci\u00f3n en 2004, Global Rescue ha sido pionera en el rescate sobre el terreno en casos de enfermedad o lesi\u00f3n, ha establecido una colaboraci\u00f3n de casi dos d\u00e9cadas con la Divisi\u00f3n de Operaciones Especiales del Departamento de Medicina de Urgencias de la Universidad Johns Hopkins y con Partners HealthCare, y sigue siendo la \u00fanica organizaci\u00f3n con personal desplegado y capacidad operativa en regiones monta\u00f1osas clave, como el Himalaya, el Karak\u00f3rum y los Andes. <\/p>\n<p>Ya sea que est\u00e9s planeando una expedici\u00f3n al Everest, una ruta de senderismo hasta el campamento base del Annapurna o una escalada en la Patagonia, la preparaci\u00f3n comienza mucho antes de poner un pie en la ruta. La afiliaci\u00f3n a Global Rescue no es un seguro, por lo que no hay formularios de reclamaci\u00f3n, franquicias ni costes inesperados. En su lugar, los miembros reciben apoyo operativo directo cuando se producen emergencias, lo que incluye rescate sobre el terreno desde el lugar donde se haya producido la enfermedad o lesi\u00f3n, evacuaci\u00f3n m\u00e9dica al hospital de su elecci\u00f3n cuando sea m\u00e9dicamente adecuado, servicios de asesoramiento m\u00e9dico las 24 horas del d\u00eda, los 7 d\u00edas de la semana, y apoyo en materia de seguridad durante desastres naturales, disturbios pol\u00edticos u otras situaciones de crisis.  <\/p>\n<p>Los informes sobre destinos de Global Rescue ofrecen informaci\u00f3n detallada sobre la capacidad m\u00e9dica local, los servicios m\u00e9dicos de urgencia, la infraestructura de rescate, los riesgos medioambientales y los puntos fuertes y las limitaciones de los sistemas sanitarios de cada destino. Estos informes ayudan a los escaladores a comprender no solo d\u00f3nde existen riesgos, sino tambi\u00e9n d\u00f3nde se encuentran los hospitales y los recursos de urgencia m\u00e1s eficaces en caso de que se produzca un incidente. <\/p>\n<p>Para los alpinistas experimentados, tomar decisiones bien fundamentadas salva vidas. Si a ello se suma la experiencia de asesores como Ed Viesturs y la capacidad operativa mundial de Global Rescue, esa preparaci\u00f3n permite a los escaladores perseguir objetivos ambiciosos con mayor confianza, sabiendo que, si ocurre algo imprevisto, hay profesionales experimentados listos para intervenir. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El legendario alpinista reflexiona sobre el Everest, el riesgo, el liderazgo, el cambio clim\u00e1tico y el futuro del alpinismo en todo el mundo.<\/p>\n","protected":false},"author":23,"featured_media":59867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1574,1477,1480],"tags":[1705,4634,1660,5019,5018,3705,3180,5020],"operation_type":[],"region":[],"class_list":["post-59871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-publicaciones-destacadas","category-viajes","tag-alpinismo","tag-cambio-climatico","tag-ed-viesturs-es","tag-escalada-alpina","tag-fiebre-de-la-cumbre","tag-gestion-de-riesgos","tag-sherpa-es","tag-zona-mortal"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/posts\/59871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/comments?post=59871"}],"version-history":[{"count":0,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/posts\/59871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/media\/59867"}],"wp:attachment":[{"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/media?parent=59871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/categories?post=59871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/tags?post=59871"},{"taxonomy":"operation_type","embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/operation_type?post=59871"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.globalrescue.com\/es\/wp-json\/wp\/v2\/region?post=59871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}